{"id":51679,"date":"2022-06-01T08:43:57","date_gmt":"2022-06-01T11:43:57","guid":{"rendered":"https:\/\/suporte.quattrus.com\/?p=51679"},"modified":"2024-07-22T21:44:25","modified_gmt":"2024-07-23T00:44:25","slug":"grafico-grafico-de-consolidacion-de-metas-en-gestiona","status":"publish","type":"post","link":"https:\/\/suporte.quattrus.com\/es\/grafico-grafico-de-consolidacion-de-metas-en-gestiona\/","title":{"rendered":"Gr\u00e1fico: Gr\u00e1fico de Consolidaci\u00f3n de Metas en Gestiona"},"content":{"rendered":"\n<p>Cuando un indicador tiene una &#8220;flecha&#8221; en la primera columna, puede ser un indicador Consolidado o Vinculado. Para averiguarlo, haga clic en la flecha y vea los indicadores debajo del indicador Principal.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-50940 alignnone size-full\" src=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero.png\" alt=\"\" width=\"1814\" height=\"555\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero.png 1814w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-600x184.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-300x92.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-1024x313.png 1024w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-768x235.png 768w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-1536x470.png 1536w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-1080x330.png 1080w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-1280x392.png 1280w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-980x300.png 980w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-480x147.png 480w\" sizes=\"auto, (max-width: 1814px) 100vw, 1814px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-50931 alignnone size-full\" src=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto.png\" alt=\"\" width=\"1815\" height=\"717\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto.png 1815w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto-600x237.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto-300x119.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto-1024x405.png 1024w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto-768x303.png 768w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto-1536x607.png 1536w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto-1080x427.png 1080w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto-1280x506.png 1280w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto-980x387.png 980w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Consolidacion-en-tablero-abierto-480x190.png 480w\" sizes=\"auto, (max-width: 1815px) 100vw, 1815px\" \/><\/p>\n<p>Si su Indicador est\u00e1 consolidaci\u00f3n, podr\u00e1 abrir el gr\u00e1fico de consolidaci\u00f3n meta e identificar cu\u00e1ntos y qu\u00e9 Indicadores est\u00e1n influyendo en sus resultados.<\/p>\n<p>Para ello, dir\u00edjase al mes deseado, haga clic en el faro y seleccione la opci\u00f3n Gr\u00e1fico de consolidaci\u00f3n de metas<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-51683 alignnone size-full\" src=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion.png\" alt=\"\" width=\"1812\" height=\"561\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion.png 1812w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-600x186.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-300x93.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-1024x317.png 1024w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-768x238.png 768w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-1536x476.png 1536w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-1080x334.png 1080w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-1280x396.png 1280w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-980x303.png 980w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-480x149.png 480w\" sizes=\"auto, (max-width: 1812px) 100vw, 1812px\" \/><\/p>\n<p>El sistema abrir\u00e1 un gr\u00e1fico que tiene la meta mensual de todos los Indicadores que Consolidaci\u00f3n su Indicador.<br \/>Los valores en verde significan que el rango alcanza la meta, los valores en amarillo, rojo y azul est\u00e1n fuera de lo esperado. Los que est\u00e1n en amarillo son los que no llegan a la meta y tienen un plan, mientras que los valores en rojo son los que no llegan a la meta y no tienen plan y los valores en azul superan la meta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-44872 alignnone size-full\" src=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37.png\" alt=\"\" width=\"748\" height=\"499\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37.png 748w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37-600x400.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37-300x200.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37-480x320.png 480w\" sizes=\"auto, (max-width: 748px) 100vw, 748px\" \/><\/p>\n<p>En la esquina superior derecha tiene dos opciones para ver el gr\u00e1fico:<\/p>\n<div class=\"accordion\">\n\n\t<div id=\"accordion-3546431832\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3546431832-label\" class=\"accordion-title plain\" href=\"#accordion-item-tipos-de-gr\u00e1ficos\" aria-expanded=\"false\" aria-controls=\"accordion-3546431832-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Tipos de Gr\u00e1ficos<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3546431832-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3546431832-label\">\n\t\t\t\n\n<p>Puede elegir ver el gr\u00e1fico en columnas o barras. Solo debe seleccionar la opci\u00f3n deseada, recordando que la visualizaci\u00f3n por defecto es en barras.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-44876 alignnone size-full\" src=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.10.08.png\" alt=\"\" width=\"747\" height=\"500\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.10.08.png 747w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.10.08-600x402.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.10.08-300x201.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.10.08-480x321.png 480w\" sizes=\"auto, (max-width: 747px) 100vw, 747px\" \/><\/p>\n<p>Al seleccionar la opci\u00f3n de columnas, ver\u00e1 el gr\u00e1fico de la siguiente manera:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-44880 alignnone size-full\" src=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.11.04.png\" alt=\"\" width=\"817\" height=\"523\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.11.04.png 817w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.11.04-600x384.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.11.04-300x192.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.11.04-768x492.png 768w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.11.04-480x307.png 480w\" sizes=\"auto, (max-width: 817px) 100vw, 817px\" \/><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2924170245\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2924170245-label\" class=\"accordion-title plain\" href=\"#accordion-item-visualizar\" aria-expanded=\"false\" aria-controls=\"accordion-2924170245-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Visualizar<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2924170245-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2924170245-label\">\n\t\t\t\n\n<p>Puede ver las metas y el proyectado de su Indicador. La opci\u00f3n meta aparecer\u00e1 marcada por defecto:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-44872 alignnone size-full\" src=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37.png\" alt=\"\" width=\"748\" height=\"499\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37.png 748w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37-600x400.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37-300x200.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2022\/06\/Snap-2022-06-20-at-23.06.37-480x320.png 480w\" sizes=\"auto, (max-width: 748px) 100vw, 748px\" \/><\/p>\n<p>En el caso de indicadores de tipo 2A, podr\u00e1 elegir ver la diferencia entre Realizado y Previsto:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-51687 alignnone size-full\" src=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-1.png\" alt=\"\" width=\"686\" height=\"497\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-1.png 686w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-1-600x435.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-1-300x217.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-1-480x348.png 480w\" sizes=\"auto, (max-width: 686px) 100vw, 686px\" \/><\/p>\n<p>Y la diferencia entre Realizo y Presupuestado:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-51690 alignnone size-full\" src=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-2.png\" alt=\"\" width=\"684\" height=\"499\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-2.png 684w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-2-600x438.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-2-300x219.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/grafico-de-consolidacion-2-480x350.png 480w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[2744,2702,2704],"tags":[2711,2712],"class_list":["post-51679","post","type-post","status-publish","format-standard","hentry","category-grafico-usuario-quattrus-es","category-quatrrus-es","category-usuario-quattrus-es","tag-quattrus","tag-quattrus-es"],"_links":{"self":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/posts\/51679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/comments?post=51679"}],"version-history":[{"count":5,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/posts\/51679\/revisions"}],"predecessor-version":[{"id":56382,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/posts\/51679\/revisions\/56382"}],"wp:attachment":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/media?parent=51679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/categories?post=51679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/tags?post=51679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}