{"id":43479,"date":"2022-05-10T00:52:19","date_gmt":"2022-05-10T03:52:19","guid":{"rendered":"https:\/\/suporte.quattrus.com\/?p=43479"},"modified":"2024-07-22T22:34:41","modified_gmt":"2024-07-23T01:34:41","slug":"referencial-amplitud-gestiona","status":"publish","type":"post","link":"https:\/\/suporte.quattrus.com\/es\/referencial-amplitud-gestiona\/","title":{"rendered":"Referencial Amplitud"},"content":{"rendered":"\n<p style=\"text-align: justify;\">Cuando utilizamos el rango verde con la previsi\u00f3n y porcentaje de tolerancia, el ICG solicita el llenado del Referencial de Amplitud tanto para el a\u00f1o como para el mes. Son estos referenciales y el porcentaje de l\u00edmite de los colores que influir\u00e1 en el ancho de su rango verde.<\/p>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; custom_margin=&#8221;-11px|||30px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>Al registrar un Indicador, en la pesta\u00f1a &#8220;Tipo de Indicador&#8221;, al seleccionar el tipo 2 (Previsi\u00f3n y % de Tolerancia), es necesario configurar las amplitudes del mes y del a\u00f1o. Haga clic para saber m\u00e1s sobre los <a href=\"https:\/\/suporte.quattrus.com\/es\/registro-de-indicadores-tipos-de-indicadores-gestiona\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tipos de Indicadores<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-51340 alignnone size-full\" src=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Tipo-de-indicador-edit-2-1.png\" alt=\"\" width=\"1099\" height=\"741\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Tipo-de-indicador-edit-2-1.png 1099w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Tipo-de-indicador-edit-2-1-600x405.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Tipo-de-indicador-edit-2-1-300x202.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Tipo-de-indicador-edit-2-1-1024x690.png 1024w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Tipo-de-indicador-edit-2-1-768x518.png 768w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Tipo-de-indicador-edit-2-1-1080x728.png 1080w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Tipo-de-indicador-edit-2-1-980x661.png 980w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/08\/Tipo-de-indicador-edit-2-1-480x324.png 480w\" sizes=\"auto, (max-width: 1099px) 100vw, 1099px\" \/><\/p>\n<p>En el campo de Referencial de Amplitud tenemos 3 opciones:<\/p>\n<figure class=\"wp-block-image\"><\/figure>\n<div class=\"accordion\">\n\n\t<div id=\"accordion-982845788\" class=\"accordion-item\">\n\t\t<a id=\"accordion-982845788-label\" class=\"accordion-title plain\" href=\"#accordion-item-variable-\u2013-previsto\" aria-expanded=\"false\" aria-controls=\"accordion-982845788-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Variable \u2013 Previsto<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-982845788-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-982845788-label\">\n\t\t\t\n\n<p>En esta opci\u00f3n siempre ser\u00e1 considerado las amplitudes referentes a los valores calculados en la columna de previsto en las mediciones. Esta es la opci\u00f3n m\u00e1s utilizada y por defecto es la opci\u00f3n que viene seleccionada al optar por un Indicador del tipo 2.<\/p>\n<p><em>Al rellenar la m\u00e1scara de<strong> importaci\u00f3n de los rangos de control<\/strong>, en el campo TP_REF_AMPLITUDE_MES y TP_REF_AMPLITUDE_A\u00d1O llene con el n\u00famero 0.<\/em><\/p>\n<p>Ejemplo:<br \/>Si define la amplitud de 10 y -10 en el rango verde, significar\u00e1 que la amplitud variar\u00e1 el 10% del valor, tanto hacia arriba, hacia abajo. Si en un mes el valor previsto es de 100, variar\u00e1 10 hacia arriba y hacia abajo, ahora, si el pr\u00f3ximo mes el valor es 120, variar\u00e1 12 hacia arriba y hacia abajo (el mismo vale para los valores anuales).<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2283061830\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2283061830-label\" class=\"accordion-title plain\" href=\"#accordion-item-variable-\u2013-m\u00ednimo\" aria-expanded=\"false\" aria-controls=\"accordion-2283061830-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Variable \u2013 M\u00ednimo<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2283061830-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2283061830-label\">\n\t\t\t\n\n<p>En esta opci\u00f3n usted deber\u00e1 proporcionar un valor fijo, adem\u00e1s de las amplitudes del mes y \/ o a\u00f1o. Si un valor calculado en las mediciones es inferior al valor fijo, la amplitud tomar\u00e1 como referencia el valor fijo, si el valor calculado es mayor que el valor fijo, la referencia ser\u00e1 el valor calculado en las mediciones.<\/p>\n<p>Al rellenar la m\u00e1scara de importaci\u00f3n de los rangos de control, en el campo TP_REF_AMPLITUDE_MES y TP_REF_AMPLITUDE_ANO llene el n\u00famero 1.<\/p>\n<p>Ejemplo:<br \/>Si se define la amplitud de 10 y -10 en el rango verde y el valor fijo es de 600, y en el mes previsto es 400 (menor que el fijo), el porcentaje de amplitud ser\u00e1 referente a los 600, es decir, variar\u00e1 60 hacia arriba y abajo. Si el pr\u00f3ximo mes se prev\u00e9 es 1000 (mayor que el fijo), el porcentaje utilizar\u00e1 lo realizado como referencia, variando 100 hacia arriba y hacia abajo.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2149598783\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2149598783-label\" class=\"accordion-title plain\" href=\"#accordion-item-fijo\" aria-expanded=\"false\" aria-controls=\"accordion-2149598783-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Fijo<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2149598783-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2149598783-label\">\n\t\t\t\n\n<p>En esta opci\u00f3n usted deber\u00e1 proporcionar un valor fijo, adem\u00e1s de las amplitudes del mes y \/ o a\u00f1o. Siempre se considerar\u00e1 las amplitudes referentes al valor fijo, independientemente del valor calculado en las previsiones.<\/p>\n<p>Al rellenar la m\u00e1scara de importaci\u00f3n de los rangos de control, en el campo TP_REF_AMPLITUDE_MES y TP_REF_AMPLITUDE_ANO rellene con el n\u00famero 2.<\/p>\n<p>Ejemplo:<br \/>Si se define la amplitud de 10 y -10 en el rango verde y el valor fijo es de 600, y en el mes previsto es 400 (menor que el fijo), el porcentaje de amplitud ser\u00e1 referente a los 600, es decir, variar\u00e1 60 hacia arriba y abajo. Si el pr\u00f3ximo mes se prev\u00e9 es 1000 (mayor que el fijo), el porcentaje continuar\u00e1 siendo referente a los 600, variando 60 hacia arriba y hacia abajo.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n<blockquote>\n<p>Recordando que las configuraciones del a\u00f1o no necesitan ser obligatoriamente igual a las del mes, incluso las amplitudes de los l\u00edmites de los colores pueden ser diferentes para el mes y el a\u00f1o.<\/p>\n<\/blockquote>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[2723,2702,2704],"tags":[425,268,213,370,473,2712,2712],"class_list":["post-43479","post","type-post","status-publish","format-standard","hentry","category-meus-indicadores-usuario-quattrus-es","category-quatrrus-es","category-usuario-quattrus-es","tag-es-cadastro-de-item-master","tag-es-faixa-cliente-master","tag-es-faixa-verde-master","tag-es-item-de-controle-master","tag-es-referencial-de-amplitude-master","tag-quattrus-es"],"_links":{"self":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/posts\/43479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/comments?post=43479"}],"version-history":[{"count":6,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/posts\/43479\/revisions"}],"predecessor-version":[{"id":56390,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/posts\/43479\/revisions\/56390"}],"wp:attachment":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/media?parent=43479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/categories?post=43479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/tags?post=43479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}