{"id":7072,"date":"2018-11-26T09:17:07","date_gmt":"2018-11-26T12:17:07","guid":{"rendered":"https:\/\/suporte2.qualitin.com\/ajuda-da-qualitin\/bonus\/"},"modified":"2024-02-01T15:00:40","modified_gmt":"2024-02-01T18:00:40","slug":"bonus","status":"publish","type":"page","link":"https:\/\/suporte.quattrus.com\/es\/ajuda-da-quattrus\/bonus\/","title":{"rendered":"B\u00f4nus"},"content":{"rendered":"\n<div class=\"row align-center\"  id=\"row-2043164286\">\n\n\n\t<div id=\"col-1344015290\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" style=\"width:30%;\">\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:90%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1500\" src=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus.png 1500w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-300x300.png 300w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-100x100.png 100w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-600x600.png 600w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-1024x1024.png 1024w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-150x150.png 150w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-768x768.png 768w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-80x80.png 80w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-1080x1080.png 1080w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-1280x1280.png 1280w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-980x980.png 980w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-480x480.png 480w, https:\/\/suporte.quattrus.com\/wp-content\/uploads\/2023\/03\/icone-bonus-60x60.png 60w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/>                         <\/div>\n          <\/div>\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">B\u00f4nus<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                                          <\/span>\n                  <\/h4>\n\t\t\t\t\t\n\n\n                <\/div>\n          <\/div>\n    <\/div>\n\n\t\n    \n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-418759820\">\n\n\n\t<div id=\"col-1491224141\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"accordion\">\n\n\t<div id=\"accordion-3071050959\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3071050959-label\" class=\"accordion-title plain\" href=\"#accordion-item-mas-leidos\" aria-expanded=\"false\" aria-controls=\"accordion-3071050959-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Mas Leidos<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3071050959-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3071050959-label\">\n\t\t\t\n\n<div class=\"rltdpstsplgn-popular-post-block\">\t\t\t<div class=\"rltdpstsplgn-popular-posts\">\n\t\t\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-aprovacion-de-metas-ajuste-en-las-amplitudes\/\">NOVEDAD: Aprovaci\u00f3n de Metas: Ajuste en las Amplitudes<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-ahora-es-mucho-mas-facil-generar-sus-reportes\/\">NOVEDAD: \u00a1Ahora es mucho m\u00e1s f\u00e1cil generar sus Reportes!<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-formalizar-tus-metas-es-aun-mas-facil\/\">NOVEDAD: \u00a1Formalizar tus Metas es a\u00fan m\u00e1s f\u00e1cil!<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-entienda-las-razones-de-los-bloqueos\/\">NOVEDAD: Entienda las razones de los Bloqueos<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-importacion-de-los-indicadores-delegados\/\">NOVEDAD: Importaci\u00f3n de los Indicadores Delegados<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t<\/div><!-- .pplrpsts-popular-posts -->\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3577437036\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3577437036-label\" class=\"accordion-title plain\" href=\"#accordion-item-preguntas-frecuentes\" aria-expanded=\"false\" aria-controls=\"accordion-3577437036-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Preguntas Frecuentes<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3577437036-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3577437036-label\">\n\t\t\t\n\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-263ba54lv4\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/que-es-evidencia-y-discricionario\/\" class=\"_blank\" target=\"_blank\" >\u00bfQu\u00e9 es Evidencia?<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/que-es-un-ciclo-de-bonus\/\" class=\"_blank\" target=\"_blank\" >\u00bfQu\u00e9 es un Ciclo de Bonus?<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/que-es-un-indicador-estandar\/\" class=\"_blank\" target=\"_blank\" >\u00bfQu\u00e9 es un Indicador Est\u00e1ndar?<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/tipos-de-reportes\/\" class=\"_blank\" target=\"_blank\" >Tipos de reportes<\/a><\/p><\/div><\/div><\/div><\/div><\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2085139852\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2085139852-label\" class=\"accordion-title plain\" href=\"#accordion-item-usuarios\" aria-expanded=\"false\" aria-controls=\"accordion-2085139852-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Usuarios<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2085139852-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2085139852-label\">\n\t\t\t\n\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-01c27dbanj\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/adjuntar-y-consultar-evidencia\/\" class=\"_blank\" target=\"_blank\" >Adjuntar y Consultar Evidencia<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-comercial-visualizacion-general-del-dashboard-del-usuario\/\" class=\"_blank\" target=\"_blank\" >Ciclo Comercial: Visualizaci\u00f3n general del dashboard del usuario<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-directoria-visualizacion-general-del-dashboard-del-usuario\/\" class=\"_blank\" target=\"_blank\" >Ciclo Directoria: Visualizaci\u00f3n general del dashboard del usuario<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/discricionario\/\" class=\"_blank\" target=\"_blank\" >Discricion\u00e1rio<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/visualizacion-general-del-dashboard-del-usuario\/\" class=\"_blank\" target=\"_blank\" >Visualizaci\u00f3n general del dashboard del usuario<\/a><\/p><\/div><\/div><\/div><\/div><\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2634283871\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2634283871-label\" class=\"accordion-title plain\" href=\"#accordion-item-administradores\" aria-expanded=\"false\" aria-controls=\"accordion-2634283871-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Administradores<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2634283871-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2634283871-label\">\n\t\t\t\n\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-c9ea527g8i\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/asignar-indicadores-estandar-a-los-usuarios-por-panel-de-administrador\/\" class=\"_blank\" target=\"_blank\" >Asignar Indicadores est\u00e1ndar a los Usuarios por panel de Administrador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-1-como-crear-un-ciclo-de-bonus\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 1: C\u00f3mo Crear un Ciclo de Bonus<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-1-personaliza-nomenclaturas\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 1: Personaliza Nomenclaturas<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-2-como-editar-atributos-del-ciclo\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 2: C\u00f3mo Editar Atributos del Ciclo<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-3-como-administrar-el-calendario-de-bloqueo\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 3: C\u00f3mo Administrar el Calendario de Bloqueo<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-4-agregar-nuevo-indicador-a-la-lista-de-indicadores\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 4: Agregar Nuevo Indicador a la Lista de Indicadores<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-5-agregar-indicador-existente-a-la-lista-de-indicadores\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 5:  Agregar Indicador Existente a la Lista de Indicadores<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-6-editar-indicadores-de-bonus\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 6: Editar Indicadores de Bonus<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-7-atribuir-indicadores-de-bonus-a-los-usuarios-por-panel-de-administrador\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 7: Atribuir Indicadores de Bonus a los Usuarios por panel de Administrador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-8-importar-y-atribuir-indicadores-de-bonus-para-los-usuarios\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 8: Importar y Atribuir Indicadores de Bonus para los usuarios<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-comercial-crear-y-editar-tablas-de-bonificacion\/\" class=\"_blank\" target=\"_blank\" >Ciclo Comercial: Crear y editar Tablas de Bonificaci\u00f3n<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-comercial-extraer-reportes-de-administrador\/\" class=\"_blank\" target=\"_blank\" >Ciclo Comercial: Extraer Reportes de Administrador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-directoria-configuracion-de-las-metas-de-la-empresa\/\" class=\"_blank\" target=\"_blank\" >Ciclo Director\u00eda: Configuraci\u00f3n de las metas de la Empresa<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-directoria-extraer-reportes-de-administarador\/\" class=\"_blank\" target=\"_blank\" >Ciclo Director\u00eda: Extraer Reportes de Administarador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/como-ver-los-archivos-adjuntos-por-administrador\/\" class=\"_blank\" target=\"_blank\" >C\u00f3mo ver los Archivos Adjuntos por Administrador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/configuracion-de-ajustes-de-calculo\/\" class=\"_blank\" target=\"_blank\" >Configuraci\u00f3n de Ajustes de Calculo<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/importacion-de-datos-por-adm\/\" class=\"_blank\" target=\"_blank\" >Importaci\u00f3n de Datos por ADM<\/a><\/p><\/div><\/div><\/div><\/div><\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-988674184\" class=\"accordion-item\">\n\t\t<a id=\"accordion-988674184-label\" class=\"accordion-title plain\" href=\"#accordion-item-versiones\" aria-expanded=\"false\" aria-controls=\"accordion-988674184-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Versiones<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-988674184-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-988674184-label\">\n\t\t\t\n\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-c1ae73di68\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/versiones-2020-bonus\/\" class=\"_blank\" target=\"_blank\" >Versiones 2020 BONUS<\/a><\/p><\/div><\/div><\/div><\/div><\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-1591178825\" class=\"text hidden\">\n\t\t\n\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;30px|0px|0px|0px|false|false&#8221; bottom_divider_color=&#8221;#029da6&#8243; bottom_divider_height=&#8221;35px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; background_enable_video_mp4=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Como podemos ajudar?&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Montserrat|700||||on|||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;60px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;40px||65px||false|false&#8221; custom_padding=&#8221;|||0px|false|false&#8221; hover_enabled=&#8221;0&#8243; text_line_height_tablet=&#8221;1em&#8221; text_line_height_phone=&#8221;&#8221; text_line_height_last_edited=&#8221;on|phone&#8221; text_text_shadow_style=&#8221;preset3&#8243; text_text_shadow_blur_strength=&#8221;0.25em&#8221; text_text_shadow_color=&#8221;#000000&#8243; global_module=&#8221;11708&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]\n<p>Como podemos ajudar?<\/p>\n[\/et_pb_text][et_pb_search exclude_pages=&#8221;on&#8221; include_categories=&#8221;16,10,57,15,45,20,48,51,62,58,12,54,43,6,46,53,17,13,7,11,139,61,59,60,339,1,49,52,19,8,18,14,55,56,44,9,47,50,912,738,914,1670,913,817,904,741,740,1671,906,901,908,812,911,737,742,910,2646,2696,2700,2647,825,2648,2649,2650,2651,2652,2653,2654,2655,2643,2656,2657,2658,2644,1987,2645&#8243; placeholder=&#8221;Descreva o problema&#8221; button_color=&#8221;#eaeaea&#8221; placeholder_color=&#8221;#666666&#8243; _builder_version=&#8221;4.16&#8243; button_font=&#8221;Montserrat|600|||||||&#8221; button_text_color=&#8221;#7c7c7c&#8221; button_font_size=&#8221;18px&#8221; form_field_font=&#8221;Montserrat||||||||&#8221; form_field_font_size=&#8221;20px&#8221; background_color=&#8221;#ffffff&#8221; max_width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||&#8221; custom_padding=&#8221;0.5em||0.5em||false|false&#8221; z_index_tablet=&#8221;500&#8243; border_radii=&#8221;on|2px|2px|2px|2px&#8221; border_width_all=&#8221;0px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;#000000&#8243; input_font=&#8221;|||||on|||&#8221; input_font_size=&#8221;25px&#8221; input_letter_spacing=&#8221;2px&#8221; input_text_shadow_horizontal_length=&#8221;input_text_shadow_style,%91object Object%93&#8243; input_text_shadow_vertical_length=&#8221;input_text_shadow_style,%91object Object%93&#8243; input_text_shadow_blur_strength=&#8221;input_text_shadow_style,%91object Object%93&#8243; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover_enabled=&#8221;on&#8221; box_shadow_color__hover=&#8221;#022f66&#8243; border_width_all__hover=&#8221;0px&#8221;]\n[\/et_pb_search][et_pb_text admin_label=&#8221;Sua busca possui o filtro B\u00f4nus.&#8221; _builder_version=&#8221;4.20.1&#8243; text_font=&#8221;|300|||||||&#8221; text_text_color=&#8221;#eaeaea&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;-12px||&#8221; text_text_shadow_style=&#8221;preset3&#8243; text_text_shadow_blur_strength=&#8221;0.25em&#8221; text_text_shadow_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]\n<p>Sua busca possui o filtro <strong>B\u00f4nus<\/strong>.<\/p>\n[\/et_pb_text][et_pb_text admin_label=&#8221;Clique aqui para pesquisar em todas categorias.&#8221; _builder_version=&#8221;4.20.1&#8243; text_font=&#8221;|300|||||||&#8221; text_text_color=&#8221;#eaeaea&#8221; link_text_color=&#8221;#ffffff&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;-26px||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><strong><a href=\"https:\/\/zns.ptf.mybluehost.me\/suporte-quattrus\/\">Clique aqui<\/a><\/strong> para pesquisar em todas categorias.<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#f9f9f9&#8243; background_enable_color=&#8221;on&#8221; custom_padding=&#8221;30px|0px|54px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; width=&#8221;45%&#8221; custom_margin=&#8221;-26px|526px|0px|526px|false|true&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_toggle title=&#8221;Mais lidos&#8221; icon_color=&#8221;#515151&#8243; open_icon_color=&#8221;#515151&#8243; admin_label=&#8221;Mais lidos&#8221; _builder_version=&#8221;4.16&#8243; title_level=&#8221;h3&#8243; title_font=&#8221;Montserrat|700|||||||&#8221; body_font=&#8221;|||||on|||&#8221; body_letter_spacing=&#8221;2px&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;0px&#8221; border_color_all=&#8221;#FFFFFF&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;]\n<div class=\"rltdpstsplgn-popular-post-block\">\t\t\t<div class=\"rltdpstsplgn-popular-posts\">\n\t\t\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-aprovacion-de-metas-ajuste-en-las-amplitudes\/\">NOVEDAD: Aprovaci\u00f3n de Metas: Ajuste en las Amplitudes<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-ahora-es-mucho-mas-facil-generar-sus-reportes\/\">NOVEDAD: \u00a1Ahora es mucho m\u00e1s f\u00e1cil generar sus Reportes!<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-formalizar-tus-metas-es-aun-mas-facil\/\">NOVEDAD: \u00a1Formalizar tus Metas es a\u00fan m\u00e1s f\u00e1cil!<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-entienda-las-razones-de-los-bloqueos\/\">NOVEDAD: Entienda las razones de los Bloqueos<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t\t<article class=\"post type-post format-standard\">\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t<h3 class=\"rltdpstsplgn_posts_title\">\t\t\t\t<a href=\"https:\/\/suporte.quattrus.com\/es\/novedad-importacion-de-los-indicadores-delegados\/\">NOVEDAD: Importaci\u00f3n de los Indicadores Delegados<\/a>\n\t\t\t\t<\/h3>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t<\/article><!-- .post -->\n\t\t\t\t\t<\/div><!-- .pplrpsts-popular-posts -->\n\t\t\t<\/div>\n[\/et_pb_toggle][et_pb_toggle title=&#8221;Perguntas Frequentes&#8221; icon_color=&#8221;#515151&#8243; open_icon_color=&#8221;#515151&#8243; admin_label=&#8221;Perguntas Frequentes&#8221; _builder_version=&#8221;4.16&#8243; title_level=&#8221;h3&#8243; title_font=&#8221;Montserrat|700|||||||&#8221; body_font=&#8221;|||||on|||&#8221; body_letter_spacing=&#8221;2px&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;0px&#8221; border_color_all=&#8221;#FFFFFF&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;]\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-263ba54lv4\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/que-es-evidencia-y-discricionario\/\" class=\"_blank\" target=\"_blank\" >\u00bfQu\u00e9 es Evidencia?<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/que-es-un-ciclo-de-bonus\/\" class=\"_blank\" target=\"_blank\" >\u00bfQu\u00e9 es un Ciclo de Bonus?<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/que-es-un-indicador-estandar\/\" class=\"_blank\" target=\"_blank\" >\u00bfQu\u00e9 es un Indicador Est\u00e1ndar?<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/tipos-de-reportes\/\" class=\"_blank\" target=\"_blank\" >Tipos de reportes<\/a><\/p><\/div><\/div><\/div><\/div><\/div>\n[\/et_pb_toggle][et_pb_toggle title=&#8221;Usu\u00e1rios&#8221; icon_color=&#8221;#515151&#8243; open_icon_color=&#8221;#515151&#8243; admin_label=&#8221;Usu\u00e1rios&#8221; _builder_version=&#8221;4.16&#8243; title_level=&#8221;h3&#8243; title_font=&#8221;Montserrat|700|||||||&#8221; body_font=&#8221;|||||on|||&#8221; body_letter_spacing=&#8221;2px&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;0px&#8221; border_color_all=&#8221;#FFFFFF&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;]\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-01c27dbanj\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/adjuntar-y-consultar-evidencia\/\" class=\"_blank\" target=\"_blank\" >Adjuntar y Consultar Evidencia<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-comercial-visualizacion-general-del-dashboard-del-usuario\/\" class=\"_blank\" target=\"_blank\" >Ciclo Comercial: Visualizaci\u00f3n general del dashboard del usuario<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-directoria-visualizacion-general-del-dashboard-del-usuario\/\" class=\"_blank\" target=\"_blank\" >Ciclo Directoria: Visualizaci\u00f3n general del dashboard del usuario<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/discricionario\/\" class=\"_blank\" target=\"_blank\" >Discricion\u00e1rio<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/visualizacion-general-del-dashboard-del-usuario\/\" class=\"_blank\" target=\"_blank\" >Visualizaci\u00f3n general del dashboard del usuario<\/a><\/p><\/div><\/div><\/div><\/div><\/div>\n[\/et_pb_toggle][et_pb_toggle title=&#8221;Administradores&#8221; icon_color=&#8221;#515151&#8243; open_icon_color=&#8221;#515151&#8243; admin_label=&#8221;Administradores&#8221; _builder_version=&#8221;4.16&#8243; title_level=&#8221;h3&#8243; title_font=&#8221;Montserrat|700|||||||&#8221; body_font=&#8221;|||||on|||&#8221; body_letter_spacing=&#8221;2px&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;0px&#8221; border_color_all=&#8221;#FFFFFF&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;]\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-c9ea527g8i\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/asignar-indicadores-estandar-a-los-usuarios-por-panel-de-administrador\/\" class=\"_blank\" target=\"_blank\" >Asignar Indicadores est\u00e1ndar a los Usuarios por panel de Administrador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-1-como-crear-un-ciclo-de-bonus\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 1: C\u00f3mo Crear un Ciclo de Bonus<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-1-personaliza-nomenclaturas\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 1: Personaliza Nomenclaturas<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-2-como-editar-atributos-del-ciclo\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 2: C\u00f3mo Editar Atributos del Ciclo<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-3-como-administrar-el-calendario-de-bloqueo\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 3: C\u00f3mo Administrar el Calendario de Bloqueo<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-4-agregar-nuevo-indicador-a-la-lista-de-indicadores\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 4: Agregar Nuevo Indicador a la Lista de Indicadores<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-5-agregar-indicador-existente-a-la-lista-de-indicadores\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 5:  Agregar Indicador Existente a la Lista de Indicadores<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-6-editar-indicadores-de-bonus\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 6: Editar Indicadores de Bonus<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-7-atribuir-indicadores-de-bonus-a-los-usuarios-por-panel-de-administrador\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 7: Atribuir Indicadores de Bonus a los Usuarios por panel de Administrador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/bonus-paso-8-importar-y-atribuir-indicadores-de-bonus-para-los-usuarios\/\" class=\"_blank\" target=\"_blank\" >Bonus &#8211; Paso 8: Importar y Atribuir Indicadores de Bonus para los usuarios<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-comercial-crear-y-editar-tablas-de-bonificacion\/\" class=\"_blank\" target=\"_blank\" >Ciclo Comercial: Crear y editar Tablas de Bonificaci\u00f3n<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-comercial-extraer-reportes-de-administrador\/\" class=\"_blank\" target=\"_blank\" >Ciclo Comercial: Extraer Reportes de Administrador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-directoria-configuracion-de-las-metas-de-la-empresa\/\" class=\"_blank\" target=\"_blank\" >Ciclo Director\u00eda: Configuraci\u00f3n de las metas de la Empresa<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/ciclo-directoria-extraer-reportes-de-administarador\/\" class=\"_blank\" target=\"_blank\" >Ciclo Director\u00eda: Extraer Reportes de Administarador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/como-ver-los-archivos-adjuntos-por-administrador\/\" class=\"_blank\" target=\"_blank\" >C\u00f3mo ver los Archivos Adjuntos por Administrador<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/configuracion-de-ajustes-de-calculo\/\" class=\"_blank\" target=\"_blank\" >Configuraci\u00f3n de Ajustes de Calculo<\/a><\/p><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/importacion-de-datos-por-adm\/\" class=\"_blank\" target=\"_blank\" >Importaci\u00f3n de Datos por ADM<\/a><\/p><\/div><\/div><\/div><\/div><\/div>\n[\/et_pb_toggle][et_pb_toggle title=&#8221;Change Log&#8221; icon_color=&#8221;#515151&#8243; open_icon_color=&#8221;#515151&#8243; admin_label=&#8221;Change Log&#8221; _builder_version=&#8221;4.16&#8243; title_level=&#8221;h3&#8243; title_font=&#8221;Montserrat|700|||||||&#8221; body_font=&#8221;|||||on|||&#8221; body_letter_spacing=&#8221;2px&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;0px&#8221; border_color_all=&#8221;#FFFFFF&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;]\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-c1ae73di68\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><p class=\"pt-cv-title\"><a href=\"https:\/\/suporte.quattrus.com\/es\/versiones-2020-bonus\/\" class=\"_blank\" target=\"_blank\" >Versiones 2020 BONUS<\/a><\/p><\/div><\/div><\/div><\/div><\/div>\n[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n\t\t\t<\/div>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":1970,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"categories":[118],"tags":[],"class_list":["post-7072","page","type-page","status-publish","hentry","category-bonus-es"],"_links":{"self":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/pages\/7072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/comments?post=7072"}],"version-history":[{"count":7,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/pages\/7072\/revisions"}],"predecessor-version":[{"id":55440,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/pages\/7072\/revisions\/55440"}],"up":[{"embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/pages\/1970"}],"wp:attachment":[{"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/media?parent=7072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/categories?post=7072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suporte.quattrus.com\/es\/wp-json\/wp\/v2\/tags?post=7072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}